{"id":87,"count":1,"description":"","link":"http:\/\/www.generalpics.com\/index.php\/tag\/%e5%85%89%e8%8d%a3%e4%b8%8e%e6%a2%a6%e6%83%b3\/","name":"\u5149\u8363\u4e0e\u68a6\u60f3","slug":"%e5%85%89%e8%8d%a3%e4%b8%8e%e6%a2%a6%e6%83%b3","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.generalpics.com\/index.php\/wp-json\/wp\/v2\/tags\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.generalpics.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.generalpics.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.generalpics.com\/index.php\/wp-json\/wp\/v2\/posts?tags=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}